{"id":31,"date":"2019-12-29T18:09:21","date_gmt":"2019-12-29T18:09:21","guid":{"rendered":"http:\/\/to-ayurveda.ch\/?page_id=31"},"modified":"2024-04-23T17:01:44","modified_gmt":"2024-04-23T15:01:44","slug":"impressum","status":"publish","type":"page","link":"https:\/\/to-ayurveda.ch\/it\/impressum\/","title":{"rendered":"Impronta e protezione dei dati"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>Impronta<\/strong><\/h2>\n\n\n\n<p><strong>Responsabile del contenuto:<\/strong><br>Franz Rutz<br>Veda Haus<br>CH-6026 Rain LU<br>E-Mail: info@to-ayurveda.ch<br>Tel: +41 (0)55 410 43 32<\/p>\n\n\n\n<p><strong>Design e programmazione:<\/strong><br>Gunnar Schr\u00f6der<br><a rel=\"noreferrer noopener\" href=\"https:\/\/www.sundara-design.com\/\" target=\"_blank\">www.sundara-design.com<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Informativa sulla privacy<\/strong><\/h2>\n\n\n\n<p>Il responsabile ai sensi delle leggi sulla protezione dei dati, in particolare del Regolamento generale sulla protezione dei dati dell&#8217;UE (DSGVO), \u00e8:<\/p>\n\n\n\n<p>Franz Rutz<br>Veda Haus<br>Chrummweid 1<br>CH-6026 Rain LU<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>I vostri diritti in materia di protezione dei dati<\/strong><\/h4>\n\n\n\n<p>Potete esercitare i seguenti diritti in qualsiasi momento utilizzando i dati di contatto forniti dal nostro responsabile della protezione dei dati:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li> Informazioni sui vostri dati memorizzati da noi e sul loro trattamento,<\/li><li> correzione dei dati personali errati<\/li><li> cancellazione dei vostri dati da noi memorizzati,<\/li><li> limitazione del trattamento dei dati se non siamo ancora autorizzati a cancellare i vostri dati a causa di obblighi legali,<\/li><li> opposizione al trattamento dei vostri dati da parte nostra, e<\/li><li> portabilit\u00e0 dei dati, a condizione che abbiate acconsentito al trattamento dei dati o abbiate stipulato un contratto con noi.<\/li><\/ul>\n\n\n\n<p>Se ci avete dato il consenso, potete revocarlo in qualsiasi momento con effetto per il futuro.<\/p>\n\n\n\n<p>Potete presentare un reclamo all&#8217;autorit\u00e0 di controllo competente per voi in qualsiasi momento. L&#8217;autorit\u00e0 di controllo competente dipende dallo Stato federale di residenza, di lavoro o di presunta violazione.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Finalit\u00e0 del trattamento dei dati da parte del titolare del trattamento e di terzi<\/strong><\/h4>\n\n\n\n<p>Trattiamo i vostri dati personali solo per gli scopi indicati nella presente informativa sulla privacy. Non trasferiamo i vostri dati personali a terzi per scopi diversi da quelli indicati. Divulgheremo i vostri dati personali a terzi solo se:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li> avete dato il vostro esplicito consenso,<\/li><li> il trattamento \u00e8 necessario per l&#8217;esecuzione di un contratto con voi,<\/li><li> il trattamento \u00e8 necessario per adempiere a un obbligo legale,<\/li><li> il trattamento \u00e8 necessario per tutelare interessi legittimi e non c&#8217;\u00e8 motivo di ritenere che abbiate un interesse legittimo prevalente a non divulgare i vostri dati.<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Cancellazione o blocco dei dati<\/strong><\/h4>\n\n\n\n<p>Ci atteniamo ai principi della prevenzione e dell&#8217;economia dei dati. Pertanto, conserviamo i vostri dati personali solo per il tempo necessario a raggiungere gli scopi qui indicati o come stabilito dai vari periodi di conservazione previsti dalla legge. Una volta cessato il rispettivo scopo o scaduti tali termini, i dati corrispondenti vengono bloccati o cancellati di routine in conformit\u00e0 alle disposizioni di legge.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Cookies<\/h4>\n\n\n\n<p>Come molti altri siti web, anche noi utilizziamo i cosiddetti &#8220;cookie&#8221;. I cookie sono piccoli file di testo che vengono trasferiti dal server di un sito web al vostro disco rigido. Questo ci fornisce automaticamente alcuni dati come l&#8217;indirizzo IP, il browser utilizzato, il sistema operativo e la vostra connessione a Internet.<\/p>\n\n\n\n<p>I cookie non possono essere utilizzati per eseguire programmi o trasmettere virus a un computer. Le informazioni contenute nei cookie ci permettono di agevolare la vostra navigazione e di visualizzare correttamente le nostre pagine web.<\/p>\n\n\n\n<p>In nessun caso i dati raccolti saranno trasmessi a terzi o collegati a dati personali senza il vostro consenso.<\/p>\n\n\n\n<p>Naturalmente, \u00e8 possibile visualizzare il nostro sito web anche senza cookie. I browser Internet sono regolarmente impostati per accettare i cookie. In generale, \u00e8 possibile disattivare l&#8217;uso dei cookie in qualsiasi momento tramite le impostazioni del browser. Per sapere come modificare queste impostazioni, utilizzate le funzioni di aiuto del vostro browser Internet. Si prega di notare che alcune funzioni del nostro sito web potrebbero non funzionare se avete disattivato l&#8217;uso dei cookie.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Crittografia SSL<\/strong><\/h4>\n\n\n\n<p>Per proteggere la sicurezza dei vostri dati durante la trasmissione, utilizziamo procedure di crittografia all&#8217;avanguardia (ad es. SSL) tramite HTTPS.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Modulo di contatto<\/strong><\/h4>\n\n\n\n<p>Se ci contattate tramite e-mail o modulo di contatto per domande di qualsiasi tipo, ci date il vostro consenso volontario per potervi contattare. A tal fine, \u00e8 necessario fornire un indirizzo e-mail valido. Questo viene utilizzato per l&#8217;assegnazione della richiesta e la successiva risposta. Il conferimento di ulteriori dati \u00e8 facoltativo. Le informazioni fornite saranno conservate per l&#8217;elaborazione della richiesta e per eventuali domande successive. I dati personali saranno cancellati automaticamente dopo l&#8217;evasione della richiesta.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Utilizzo di librerie di script (Google Webfonts)<\/strong><\/h4>\n\n\n\n<p>Per visualizzare i nostri contenuti in modo corretto e graficamente accattivante su tutti i browser, su questo sito web utilizziamo librerie di script e di font come Google Webfonts (https:\/\/www.google.com\/webfonts\/). I Google Webfonts vengono trasferiti nella cache del browser per evitare caricamenti multipli. Se il browser non supporta Google Web Fonts o ne impedisce l&#8217;accesso, il contenuto viene visualizzato con un font standard.<\/p>\n\n\n\n<p>Il richiamo di librerie di script o di font attiva automaticamente una connessione con il gestore della libreria. \u00c8 teoricamente possibile &#8211; anche se attualmente non \u00e8 chiaro se e per quali scopi &#8211; che i gestori di tali librerie raccolgano dati.<\/p>\n\n\n\n<p>L&#8217;informativa sulla privacy dell&#8217;operatore della libreria Google pu\u00f2 essere consultata qui: <a href=\"https:\/\/www.google.com\/policies\/privacy\/\">https:\/\/www.google.com\/policies\/privacy\/<\/a><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Modifiche alla nostra informativa sulla privacy<\/strong><\/h4>\n\n\n\n<p>Ci riserviamo il diritto di adeguare la presente dichiarazione sulla protezione dei dati in modo che sia sempre conforme ai requisiti legali vigenti o per attuare modifiche ai nostri servizi nella dichiarazione sulla protezione dei dati, ad esempio in occasione dell&#8217;introduzione di nuovi servizi. La nuova dichiarazione sulla protezione dei dati si applicher\u00e0 alla vostra prossima visita.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Impronta Responsabile del contenuto:Franz RutzVeda HausCH-6026 Rain LUE-Mail: info@to-ayurveda.chTel: +41 (0)55 410 43 32 Design e programmazione:Gunnar Schr\u00f6derwww.sundara-design.com Informativa sulla privacy Il responsabile ai sensi delle leggi sulla protezione dei dati, in particolare del Regolamento generale sulla protezione dei dati dell&#8217;UE (DSGVO), \u00e8: Franz RutzVeda HausChrummweid 1CH-6026 Rain LU I vostri diritti in materia di [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","footnotes":""},"class_list":["post-31","page","type-page","status-publish","hentry","entry"],"_links":{"self":[{"href":"https:\/\/to-ayurveda.ch\/it\/wp-json\/wp\/v2\/pages\/31","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/to-ayurveda.ch\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/to-ayurveda.ch\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/to-ayurveda.ch\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/to-ayurveda.ch\/it\/wp-json\/wp\/v2\/comments?post=31"}],"version-history":[{"count":2,"href":"https:\/\/to-ayurveda.ch\/it\/wp-json\/wp\/v2\/pages\/31\/revisions"}],"predecessor-version":[{"id":614,"href":"https:\/\/to-ayurveda.ch\/it\/wp-json\/wp\/v2\/pages\/31\/revisions\/614"}],"wp:attachment":[{"href":"https:\/\/to-ayurveda.ch\/it\/wp-json\/wp\/v2\/media?parent=31"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}